{"id":4551,"date":"2025-01-15T11:08:13","date_gmt":"2025-01-15T11:08:13","guid":{"rendered":"https:\/\/undo.be\/les-couts-caches-de-rester-connecte\/"},"modified":"2025-01-15T13:09:23","modified_gmt":"2025-01-15T13:09:23","slug":"les-couts-caches-de-rester-connecte","status":"publish","type":"post","link":"https:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/","title":{"rendered":"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9"},"content":{"rendered":"\n<section class=\"cta\">\n  <div class=\"cta__inner\">\n          \n\n\n<figure class=\"image image_fit-contain cta__image\"\n  style=\"--aspect-ratio: 1\">\n  <img decoding=\"async\" src=\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.webp\" alt=\"\" \/>\n<\/figure>    \n    <div class=\"cta__content\">\n      \n              \n\n<h2 class=\"heading heading_as-h2 cta__content-title\">\n  Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9.\n<\/h2>\n      \n              \n\n\n<div class=\"text text_default-16 cta__content-description\" >\n  Alors que le monde devient de plus en plus connect\u00e9, il est temps de r\u00e9fl\u00e9chir aux co\u00fbts invisibles de nos vies num\u00e9riques. Une consommation consciente \u2013 une approche consciente de la fa\u00e7on dont nous utilisons et achetons \u2013 peut faire une diff\u00e9rence significative, m\u00eame \u00e0 l&#8217;\u00e8re du mobile. \n<\/div>\n      \n              \n\n\n<a class=\"button button_variant-primary button_scheme-light cta__content-link\" href=\"https:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#smartphones\" target=\"\">\n  \n      <span class=\"button__label\">D\u00e9couvrez-le<\/span>\n  \n  <\/a>\n          <\/div>\n  <\/div>\n<\/section>\n<style>\n@media (min-width: 1025px) {\n  .info {\n    --info-inner-template-columns: repeat(3, 1fr);\n  }\n}\n<\/style>\n<section id=\"smartphones\" class=\"info \">\n  <div class=\"info__inner\">\n          \n\n\n<div class=\"text text_default-18 info__header\" >\n  <h1>Le <b>bilan \u00e9cologique des smartphones et de la connectivit\u00e9<\/b>.<\/h1>\n\n<\/div>\n    \n                  <div class=\"info__column\">\n                      \n\n\n<figure class=\"image image_fit-contain info__column-image\"\n  style=\"--aspect-ratio: 1\">\n  <img decoding=\"async\" src=\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO3-e1736937697550.webp\" alt=\"\" \/>\n<\/figure>          \n                      \n\n<h3 class=\"heading heading_as-h3 info__column-title\">\n  Smartphones et d\u00e9chets \u00e9lectroniques\n<\/h3>\n          \n                      \n\n\n<div class=\"text text_default-18 info__column-content\" >\n  <p>Chaque nouveau smartphone entra\u00eene des co\u00fbts cach\u00e9s : <\/p>\n<ul>\n<li aria-level=\"1\">&#8211; \u00c9puisement des ressources : des mat\u00e9riaux comme le cobalt et le lithium, essentiels aux batteries des smartphones, sont extraits dans des conditions environnementales et sociales n\u00e9fastes.<\/li>\n<li aria-level=\"1\">&#8211; Crise des d\u00e9chets \u00e9lectroniques : <a href=\"https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/electronic-waste-(e-waste)#:~:text=Key%20facts,collected%20and%20recycled%20(2).\">En 2022, 62 millions de tonnes de d\u00e9chets \u00e9lectroniques ont \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9es dans le monde, mais seulement 22,3 % ont \u00e9t\u00e9 recycl\u00e9s.<\/a><\/li>\n<\/ul>\n<p> L\u2019upgrade fr\u00e9quent des smartphones ne fait qu\u2019augmenter la pile d\u2019appareils mis au tiroir. La solution ? Optez pour des smartphones reconditionn\u00e9s ou r\u00e9parez votre t\u00e9l\u00e9phone existant au lieu de le remplacer.  <\/p>\n\n<\/div>\n                  <\/div>\n              <div class=\"info__column\">\n                      \n\n\n<figure class=\"image image_fit-contain info__column-image\"\n  style=\"--aspect-ratio: 1\">\n  <img decoding=\"async\" src=\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/16-e1736937719442.webp\" alt=\"\" \/>\n<\/figure>          \n                      \n\n<h3 class=\"heading heading_as-h3 info__column-title\">\n  L&#8217;empreinte carbone de la consommation de donn\u00e9es mobiles\n<\/h3>\n          \n                      \n\n\n<div class=\"text text_default-18 info__column-content\" >\n  <p>Les r\u00e9seaux \u00e0 haut d\u00e9bit comme la 5G promettent une efficacit\u00e9, mais la demande accrue de streaming, de jeux et d\u2019IoT entra\u00eene une plus grande consommation d\u2019\u00e9nergie. Quel que soit l\u2019avantage, notre consommation num\u00e9rique laisse une empreinte carbone importante. <\/p>\n\n<\/div>\n                  <\/div>\n              <div class=\"info__column\">\n                      \n\n\n<figure class=\"image image_fit-contain info__column-image\"\n  style=\"--aspect-ratio: 1\">\n  <img decoding=\"async\" src=\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/17-e1736937708888.webp\" alt=\"\" \/>\n<\/figure>          \n                      \n\n<h3 class=\"heading heading_as-h3 info__column-title\">\n  Fatigue num\u00e9rique\n<\/h3>\n          \n                      \n\n\n<div class=\"text text_default-18 info__column-content\" >\n  <p>Une connectivit\u00e9 permanente a un impact sur le bien-\u00eatre mental. Les notifications, le d\u00e9filement sans fin sur son \u00e9cran et la gratification instantan\u00e9e peuvent entra\u00eener du stress et r\u00e9duire la capacit\u00e9 d&#8217;attention. Trouver un \u00e9quilibre profite \u00e0 la fois \u00e0 notre sant\u00e9 et \u00e0 la plan\u00e8te.  <\/p>\n\n<\/div>\n                  <\/div>\n            <\/div>\n<\/section>\n\n<section class=\"newsletter \">\n  <div class=\"newsletter__inner\">\n          \n\n\n<figure class=\"image image_fit-contain newsletter__image\"\n  style=\"--aspect-ratio: 1.0912408759124\">\n  <img decoding=\"async\" src=\"https:\/\/undo.be\/wp-content\/uploads\/2024\/06\/calc-phone1.d2dca050-1200x0-c-default.webp\" alt=\"\" \/>\n<\/figure>    \n    <div class=\"newsletter__form\">\n      <div class=\"newsletter__form-inner\">\n                  \n\n\n<div class=\"text text_default-16 newsletter__form-description\" >\n  <h1>Comment vous pouvez agir !<\/h1>\n<p>&nbsp;<\/p>\n<h4><i>Lutter contre les d\u00e9chets \u00e9lectroniques<\/i><\/h4>\n<ol>\n<li aria-level=\"1\">1. <strong>Choisissez des t\u00e9l\u00e9phones reconditionn\u00e9s<\/strong> sur des plateformes certifi\u00e9es comme Refurbed.be, Backmarket ou Valyuu.<\/li>\n<li aria-level=\"1\">2. <strong>R\u00e9parez vos appareils<\/strong> au lieu de les remplacer.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h4><i>R\u00e9duisez la consommation de donn\u00e9es mobiles<\/i><\/h4>\n<ol>\n<li aria-level=\"1\">1. <strong>Streamez \u00e0 des r\u00e9solutions inf\u00e9rieures<\/strong> ou d\u00e9sactivez la lecture automatique.<\/li>\n<li aria-level=\"1\">2. <strong>Utilisez le Wi-Fi<\/strong> autant que possible.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h4><i>Optez pour des abonnements neutres en carbone<\/i><\/h4>\n<ol>\n<li>1. <strong>Avec UNDO, chaque connexion est neutre en carbone<\/strong>. Suivez l&#8217;empreinte carbone de votre utilisation mobile, r\u00e9duisez votre impact et compensez vos \u00e9missions, le tout via notre application. <\/li>\n<\/ol>\n\n<\/div>\n        \n              <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n<section \n  class=\"tb tb_green  \">\n  <div class=\"tb__inner\">\n          \n\n\n<div class=\"text text_default-18 tb__content\" >\n  <h2><b>Suivez votre impact avec le UNDO Tracker<\/b><\/h2>\n<p> Vous \u00eates-vous d\u00e9j\u00e0 demand\u00e9 quel \u00e9tait l\u2019impact de votre utilisation mobile sur la plan\u00e8te ? Le UNDO Tracker met le pouvoir entre vos mains, vous aidant \u00e0 :  <\/p>\n<ul>\n<li aria-level=\"1\">Mesurer votre empreinte carbone en temps r\u00e9el.<\/li>\n<li aria-level=\"1\">Suivre vos progr\u00e8s vers des habitudes plus durables.<\/li>\n<li aria-level=\"1\">Compenser vos \u00e9missions facilement gr\u00e2ce \u00e0 votre abonnement.<\/li>\n<\/ul>\n<p> Avec le UNDO Tracker, chaque choix r\u00e9fl\u00e9chi que vous faites, comme r\u00e9duire la consommation de donn\u00e9es mobiles ou prolonger la dur\u00e9e de vie de votre smartphone, cr\u00e9e un impact visible et positif. <\/p>\n<h2><\/h2>\n<h2><b>Faisons en sorte que chaque connexion compte<\/b><\/h2>\n<p> \u00c0 mesure que nous avan\u00e7ons, n\u2019oubliez pas que de petits choix conscients peuvent avoir un impact important. Qu\u2019il s\u2019agisse de <strong>r\u00e9duire votre empreinte num\u00e9rique<\/strong>, d\u2019<strong>opter pour des appareils reconditionn\u00e9s<\/strong> ou de <strong>soutenir des initiatives durables comme UNDO Forest<\/strong>, chaque action contribue \u00e0 un monde plus vert et plus connect\u00e9. <\/p>\n\n<\/div>\n    \n          <div class=\"tb__buttons\">\n                  \n\n\n<a class=\"button button_variant-outlined button_scheme-dark\" href=\"https:\/\/undo.be\/fr\/app\/\" target=\"\">\n  \n      <span class=\"button__label\">D\u00e9couvre l&#8217;app UNDO<\/span>\n  \n  <\/a>\n                  \n\n\n<a class=\"button button_variant-primary button_scheme-dark\" href=\"https:\/\/undo.be\/fr\/abonnements-mobiles\/#mobile-subscriptions\" target=\"\">\n  \n      <span class=\"button__label\">D\u00e9couvrez nos abonnements<\/span>\n  \n  <\/a>\n              <\/div>\n      <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le monde devient de plus en plus connect\u00e9, il est temps de r\u00e9fl\u00e9chir aux co\u00fbts invisibles de nos vies num\u00e9riques.<\/p>\n","protected":false},"author":2,"featured_media":4471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo\" \/>\n<meta property=\"og:description\" content=\"Alors que le monde devient de plus en plus connect\u00e9, il est temps de r\u00e9fl\u00e9chir aux co\u00fbts invisibles de nos vies num\u00e9riques.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/\" \/>\n<meta property=\"og:site_name\" content=\"Undo\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T11:08:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T13:09:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"undo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"undo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/\",\"url\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/\",\"name\":\"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo\",\"isPartOf\":{\"@id\":\"http:\/\/undo.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png\",\"datePublished\":\"2025-01-15T11:08:13+00:00\",\"dateModified\":\"2025-01-15T13:09:23+00:00\",\"author\":{\"@id\":\"http:\/\/undo.be\/#\/schema\/person\/b0ab01928a6f0b57a5d44fbfc2ef4ec9\"},\"breadcrumb\":{\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage\",\"url\":\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png\",\"contentUrl\":\"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/undo.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/undo.be\/#website\",\"url\":\"http:\/\/undo.be\/\",\"name\":\"Undo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/undo.be\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/undo.be\/#\/schema\/person\/b0ab01928a6f0b57a5d44fbfc2ef4ec9\",\"name\":\"undo\",\"url\":\"https:\/\/undo.be\/fr\/author\/undo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo","og_description":"Alors que le monde devient de plus en plus connect\u00e9, il est temps de r\u00e9fl\u00e9chir aux co\u00fbts invisibles de nos vies num\u00e9riques.","og_url":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/","og_site_name":"Undo","article_published_time":"2025-01-15T11:08:13+00:00","article_modified_time":"2025-01-15T13:09:23+00:00","og_image":[{"width":1024,"height":1024,"url":"http:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png","type":"image\/png"}],"author":"undo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"undo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/","url":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/","name":"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9 - Undo","isPartOf":{"@id":"http:\/\/undo.be\/#website"},"primaryImageOfPage":{"@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage"},"image":{"@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage"},"thumbnailUrl":"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png","datePublished":"2025-01-15T11:08:13+00:00","dateModified":"2025-01-15T13:09:23+00:00","author":{"@id":"http:\/\/undo.be\/#\/schema\/person\/b0ab01928a6f0b57a5d44fbfc2ef4ec9"},"breadcrumb":{"@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#primaryimage","url":"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png","contentUrl":"https:\/\/undo.be\/wp-content\/uploads\/2025\/01\/Disconnect-with-UNDO.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"http:\/\/undo.be\/fr\/les-couts-caches-de-rester-connecte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/undo.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Co\u00fbts Cach\u00e9s de Rester Connect\u00e9"}]},{"@type":"WebSite","@id":"http:\/\/undo.be\/#website","url":"http:\/\/undo.be\/","name":"Undo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/undo.be\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/undo.be\/#\/schema\/person\/b0ab01928a6f0b57a5d44fbfc2ef4ec9","name":"undo","url":"https:\/\/undo.be\/fr\/author\/undo\/"}]}},"_links":{"self":[{"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/posts\/4551"}],"collection":[{"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/comments?post=4551"}],"version-history":[{"count":4,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/posts\/4551\/revisions"}],"predecessor-version":[{"id":4570,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/posts\/4551\/revisions\/4570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/media\/4471"}],"wp:attachment":[{"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/categories?post=4551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/undo.be\/fr\/wp-json\/wp\/v2\/tags?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}